{"id":3200,"date":"2025-06-13T18:07:39","date_gmt":"2025-06-13T16:07:39","guid":{"rendered":"https:\/\/mutuallogistics.com\/?page_id=3200"},"modified":"2025-07-11T16:38:55","modified_gmt":"2025-07-11T14:38:55","slug":"our-job-offers","status":"publish","type":"page","link":"https:\/\/mutuallogistics.com\/en\/nos-offres-demploi\/","title":{"rendered":"Nos offres d&#8217;emploi"},"content":{"rendered":"<div id=\"fws_6a044ce5a61cd\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"9%\" data-bottom-percent=\"9%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section parallax_section mobile-disable-bg-image-animation\"  style=\"padding-top: calc(100vw * 0.09); padding-bottom: calc(100vw * 0.09); \"><div class=\"row-bg-wrap\" data-bg-animation=\"zoom-out-slow\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image using-bg-color\" data-parallax-speed=\"fast\" style=\"background-image: url(https:\/\/mutuallogistics.com\/wp-content\/uploads\/2025\/05\/mutual_logistics_02_1280x720.jpg); background-position: center center; background-repeat: no-repeat; background-color: #aa9a72; \"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: rgba(20,20,19,0.85); background: linear-gradient(45deg,rgba(20,20,19,0.85) 0%,rgba(70,70,68,0.42) 100%);  opacity: 0.95; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light center\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<h1 style=\"text-align: center\" class=\"vc_custom_heading vc_do_custom_heading wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp vc_custom_1752057966262\" >Our job offers<\/h1>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a044ce5a6e4b\"  data-column-margin=\"60px\" data-midnight=\"dark\" data-top-percent=\"5%\" data-bottom-percent=\"2%\"  class=\"wpb_row vc_row-fluid vc_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle  reverse_columns_column_tablet reverse_columns_column_phone bottom_padding_tablet_60px bottom_padding_phone_80px\"  style=\"padding-top: calc(100vw * 0.05); padding-bottom: calc(100vw * 0.02); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div style=\"margin-top: 20px; \" class=\"vc_col-sm-8 wpb_column column_container vc_column_container col has-animation no-extra-padding inherit_tablet inherit_phone mobile-disable-entrance-animation\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<h2 style=\"text-align: left\" class=\"vc_custom_heading vc_do_custom_heading vc_custom_1752044827884\" >OUR <strong>HR POLICY<\/strong><\/h2>\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp vc_custom_1752044867512\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Committed to the fight against discrimination and the defence of equal opportunities, Mutual logistics has signed the Diversity Charter, placing skills at the heart of human resources management. Discover our job offers for <strong>logistics professions<\/strong>\u00a0for the transport, warehousing and overseas sectors.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a044ce5a796f\"  data-column-margin=\"default\" data-midnight=\"dark\" data-bottom-percent=\"5%\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: calc(100vw * 0.05); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"portfolio-wrap\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<span class=\"portfolio-loading  none\">   <\/span>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"row portfolio-items no-masonry\" data-rcp=\"false\" data-masonry-type=\"default\" data-ps=\"9\" data-starting-filter=\"\" data-gutter=\"default\" data-categories-to-show=\"\" data-bypass-cropping=\"\" data-lightbox-only=\"0\" data-col-num=\"cols-4\">\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col span_3  element\"  data-project-cat=\"\" data-default-color=\"true\" data-title-color=\"\" data-subtitle-color=\"\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"inner-wrap animated\" data-animation=\"fade_in_from_bottom\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-item style-1\" data-custom-content=\"off\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"size- skip-lazy\" src=\"https:\/\/mutuallogistics.com\/wp-content\/uploads\/2025\/07\/mutual_logistics_09_1280x720-600x403.jpg\" alt=\"\" height=\"403\" width=\"600\" srcset=\"https:\/\/mutuallogistics.com\/wp-content\/uploads\/2025\/07\/mutual_logistics_09_1280x720-900x604.jpg 900w, https:\/\/mutuallogistics.com\/wp-content\/uploads\/2025\/07\/mutual_logistics_09_1280x720-600x403.jpg 600w, https:\/\/mutuallogistics.com\/wp-content\/uploads\/2025\/07\/mutual_logistics_09_1280x720-400x269.jpg 400w\" sizes=\"auto, (min-width: 1000px) 25vw, (min-width: 690px) 50vw, 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"work-info\"> \n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/mutuallogistics.com\/en\/offre\/preparateur-de-commande-h-f\/\"><span class=\"screen-reader-text\">Order picker (M\/F)<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div><!--work-item-->\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"work-meta\">\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"title\">Order picker (M\/F)<\/h4>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<p>Working for our Poupry site and reporting to your Business Manager, your primary function will be to prepare orders for...<\/p>\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div><!--\/inner-wrap-->\n\t\t\t\t\t\t<\/div><!--\/col-->\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div><!--\/portfolio-->\n\t\t\t<\/div><!--\/portfolio wrap-->\n\t\t\t\n\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a044ce5a8cf2\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"2%\" data-bottom-percent=\"2%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section vc_row-o-equal-height vc_row-flex vc_row-o-content-middle parallax_section top_padding_phone_40px bottom_padding_phone_60px\"  style=\"padding-top: calc(100vw * 0.02); padding-bottom: calc(100vw * 0.02); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\" data-parallax-speed=\"fixed\" style=\"background-color: #AA9A72; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><h4 style=\"text-align: left\" class=\"vc_custom_heading vc_do_custom_heading wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp vc_custom_1752058372724\" >Can't find a vacancy that matches your requirements, but think you have the ideal profile to join our teams?<\/h4>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col no-extra-padding force-desktop-text-align-center inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<a class=\"nectar-button medium see-through-2  wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp\"  role=\"button\" style=\"\"  href=\"https:\/\/mutuallogistics.com\/en\/unsolicited-application\/\" data-color-override=\"false\"  data-hover-color-override=\"#CEB888\" data-hover-text-color-override=\"#ffffff\"><span>SUBMIT AN UNSOLICITED APPLICATION<\/span><\/a>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2986,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"D\u00e9couvrez nos offres d\u2019emploi pour les m\u00e9tiers de la logistique : pour les secteurs du transport, de l\u2019entreposage et de l\u2019overseas...","_seopress_robots_index":"","inline_featured_image":false,"footnotes":""},"class_list":["post-3200","page","type-page","status-publish","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/mutuallogistics.com\/en\/wp-json\/wp\/v2\/pages\/3200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mutuallogistics.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mutuallogistics.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mutuallogistics.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mutuallogistics.com\/en\/wp-json\/wp\/v2\/comments?post=3200"}],"version-history":[{"count":12,"href":"https:\/\/mutuallogistics.com\/en\/wp-json\/wp\/v2\/pages\/3200\/revisions"}],"predecessor-version":[{"id":3373,"href":"https:\/\/mutuallogistics.com\/en\/wp-json\/wp\/v2\/pages\/3200\/revisions\/3373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mutuallogistics.com\/en\/wp-json\/wp\/v2\/media\/2986"}],"wp:attachment":[{"href":"https:\/\/mutuallogistics.com\/en\/wp-json\/wp\/v2\/media?parent=3200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}